{"id":132612,"date":"2026-05-04T15:03:25","date_gmt":"2026-05-04T15:03:25","guid":{"rendered":"https:\/\/indogenmed.org\/product\/cardivas-3125-mg-tablets\/"},"modified":"2026-08-22T17:57:43","modified_gmt":"2026-08-22T17:57:43","slug":"cardivas-3125-mg-tablets","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/cardivas-3125-mg-tablets\/","title":{"rendered":"Cardivas 3.125 mg Comprim\u00e9s"},"content":{"rendered":"<p><strong>Cardivas<\/strong> 3.125 Mg Tablets est disponible chez Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9.<\/p>\n<p>Veuillez utiliser ce m\u00e9dicament uniquement sous un avis m\u00e9dical qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e du traitement prescrites.<\/p>\n<p>Pour les demandes en gros, la disponibilit\u00e9 et l&rsquo;assistance \u00e0 l&rsquo;exp\u00e9dition, contactez l&rsquo;\u00e9quipe d&rsquo;assistance d&rsquo;Indogenmed avant de passer commande.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cardivas 3.125 Mg Tablets est disponible chez Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9. Veuillez utiliser ce m\u00e9dicament uniquement sous un avis m\u00e9dical qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e du traitement prescrites. Pour les demandes en gros, la disponibilit\u00e9 et l&rsquo;assistance \u00e0 l&rsquo;exp\u00e9dition, contactez l&rsquo;\u00e9quipe d&rsquo;assistance d&rsquo;Indogenmed avant de [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[16301],"product_tag":[15902,15901],"igm_manufacturer":[],"class_list":["post-132612","product","type-product","status-publish","product_cat-heart-medicines","product_tag-strip","product_tag-tablet","pa_brand-name-cardivas","pa_molecule-carvedilol","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/132612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=132612"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=132612"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=132612"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=132612"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=132612"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=132612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}