{"id":133539,"date":"2026-05-04T15:01:21","date_gmt":"2026-05-04T15:01:21","guid":{"rendered":"https:\/\/indogenmed.org\/product\/montair-10-mg-tablets\/"},"modified":"2026-08-23T13:51:29","modified_gmt":"2026-08-23T13:51:29","slug":"montair-10-mg-tablets","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/montair-10-mg-tablets\/","title":{"rendered":"Comprim\u00e9s Montair 10 Mg"},"content":{"rendered":"<p><strong>Montair<\/strong> 10 Mg en comprim\u00e9s est disponible chez Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9.<\/p>\n<p>Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision d&rsquo;un professionnel de sant\u00e9 qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e de traitement prescrites.<\/p>\n<p>Pour toute demande en gros, toute question de disponibilit\u00e9 ou d&rsquo;assistance \u00e0 l&rsquo;exp\u00e9dition, veuillez contacter l&rsquo;\u00e9quipe de support d&rsquo;Indogenmed avant de passer commande.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Montair 10 Mg en comprim\u00e9s est disponible chez Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9. Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision d&rsquo;un professionnel de sant\u00e9 qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e de traitement prescrites. Pour toute demande en gros, toute question de disponibilit\u00e9 ou d&rsquo;assistance \u00e0 l&rsquo;exp\u00e9dition, [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[16254],"product_tag":[21830,15902,15901],"igm_manufacturer":[],"class_list":["post-133539","product","type-product","status-publish","product_cat-mens-health-wellness","product_tag-montelukast","product_tag-strip","product_tag-tablet","pa_brand-name-montair","pa_molecule-montelukast","first","outofstock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/133539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=133539"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=133539"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=133539"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=133539"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=133539"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=133539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}