{"id":133724,"date":"2026-05-04T15:01:12","date_gmt":"2026-05-04T15:01:12","guid":{"rendered":"https:\/\/indogenmed.org\/product\/my-hep-400-mg-tablets\/"},"modified":"2026-08-24T14:28:34","modified_gmt":"2026-08-24T14:28:34","slug":"my-hep-400-mg-tablets","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/my-hep-400-mg-tablets\/","title":{"rendered":"Comprim\u00e9s My Hep 400 Mg"},"content":{"rendered":"<p><strong>My Hep<\/strong> 400 Mg, comprim\u00e9s, est disponible chez Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9.<\/p>\n<p>Veuillez n&rsquo;utiliser ce m\u00e9dicament que sous la supervision d&rsquo;un professionnel de sant\u00e9 qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e du traitement prescrites.<\/p>\n<p>Pour toute demande concernant des commandes en gros, la disponibilit\u00e9 ou l&rsquo;exp\u00e9dition, veuillez contacter l&rsquo;\u00e9quipe d&rsquo;assistance d&rsquo;Indogenmed avant de passer commande.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>My Hep 400 Mg, comprim\u00e9s, est disponible chez Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9. Veuillez n&rsquo;utiliser ce m\u00e9dicament que sous la supervision d&rsquo;un professionnel de sant\u00e9 qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e du traitement prescrites. Pour toute demande concernant des commandes en gros, la disponibilit\u00e9 ou l&rsquo;exp\u00e9dition, veuillez [&hellip;]<\/p>\n","protected":false},"featured_media":133725,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[16254],"product_tag":[20206,15902,15901],"igm_manufacturer":[],"class_list":["post-133724","product","type-product","status-publish","has-post-thumbnail","product_cat-mens-health-wellness","product_tag-sofosbuvir","product_tag-strip","product_tag-tablet","pa_brand-name-my-hep","pa_molecule-sofosbuvir","first","outofstock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/133724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=133724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media\/133725"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=133724"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=133724"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=133724"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=133724"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=133724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}