{"id":133731,"date":"2026-05-04T15:01:05","date_gmt":"2026-05-04T15:01:05","guid":{"rendered":"https:\/\/indogenmed.org\/product\/oflox-5-ml-tablets\/"},"modified":"2026-08-28T04:13:51","modified_gmt":"2026-08-28T04:13:51","slug":"oflox-5-ml-tablets","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/oflox-5-ml-tablets\/","title":{"rendered":"Oflox 5 Ml"},"content":{"rendered":"<p><strong>Oflox<\/strong> 5 Ml Tablets est disponible chez Indogenmed pour un acc\u00e8s fiable aux produits pharmaceutiques de qualit\u00e9.<\/p>\n<p>Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision m\u00e9dicale qualifi\u00e9e. Respectez toujours la posologie prescrite et la dur\u00e9e du traitement.<\/p>\n<p>Pour les demandes en gros, la disponibilit\u00e9 et le soutien \u00e0 l&rsquo;exp\u00e9dition, contactez l&rsquo;\u00e9quipe de soutien d&rsquo;Indogenmed avant de passer commande.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oflox 5 Ml Tablets est disponible chez Indogenmed pour un acc\u00e8s fiable aux produits pharmaceutiques de qualit\u00e9. Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision m\u00e9dicale qualifi\u00e9e. Respectez toujours la posologie prescrite et la dur\u00e9e du traitement. Pour les demandes en gros, la disponibilit\u00e9 et le soutien \u00e0 l&rsquo;exp\u00e9dition, contactez l&rsquo;\u00e9quipe de soutien d&rsquo;Indogenmed avant [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[16254],"product_tag":[16836,24838,16682],"igm_manufacturer":[],"class_list":["post-133731","product","type-product","status-publish","product_cat-mens-health-wellness","product_tag-eye-drops","product_tag-ofloxacin","product_tag-vial-bottle","pa_brand-name-oflox","pa_molecule-ofloxacin","first","outofstock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/133731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=133731"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=133731"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=133731"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=133731"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=133731"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=133731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}