{"id":134786,"date":"2026-05-04T14:57:38","date_gmt":"2026-05-04T14:57:38","guid":{"rendered":"https:\/\/indogenmed.org\/product\/nevanac-eye-5-ml-eye-drops\/"},"modified":"2026-08-25T21:28:12","modified_gmt":"2026-08-25T21:28:12","slug":"nevanac-eye-5-ml-eye-drops","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/nevanac-eye-5-ml-eye-drops\/","title":{"rendered":"Collyre Nevanac Eye 5 ml"},"content":{"rendered":"<p><strong>Nevanac Eye Eye<\/strong> Gouttes 5 Ml est disponible chez Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9.<\/p>\n<p>Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision d&rsquo;un m\u00e9decin qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e du traitement prescrites.<\/p>\n<p>Pour toute demande en gros, toute question de disponibilit\u00e9 ou une assistance \u00e0 l&rsquo;exp\u00e9dition, veuillez contacter l&rsquo;\u00e9quipe support d&rsquo;Indogenmed avant de passer commande.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nevanac Eye Eye Gouttes 5 Ml est disponible chez Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9. Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision d&rsquo;un m\u00e9decin qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e du traitement prescrites. Pour toute demande en gros, toute question de disponibilit\u00e9 ou une assistance \u00e0 l&rsquo;exp\u00e9dition, [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[11263],"product_tag":[16836,16682],"igm_manufacturer":[],"class_list":["post-134786","product","type-product","status-publish","product_cat-glaucoma-fr","product_tag-eye-drops","product_tag-vial-bottle","pa_brand-name-nevanac","pa_molecule-nepafenac","first","outofstock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/134786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=134786"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=134786"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=134786"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=134786"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=134786"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=134786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}