{"id":135526,"date":"2026-05-04T14:54:18","date_gmt":"2026-05-04T14:54:18","guid":{"rendered":"https:\/\/indogenmed.org\/product\/moxif-400-mg-tablets\/"},"modified":"2026-08-26T00:25:39","modified_gmt":"2026-08-26T00:25:39","slug":"moxif-400-mg-tablets","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/moxif-400-mg-tablets\/","title":{"rendered":"Comprim\u00e9s Moxif 400 Mg"},"content":{"rendered":"<p>Les comprim\u00e9s <strong>Moxif<\/strong> 400 Mg sont disponibles sur Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9.<\/p>\n<p>Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision d&rsquo;un professionnel de sant\u00e9 qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e du traitement prescrites.<\/p>\n<p>Pour toute demande concernant les commandes en gros, la disponibilit\u00e9 ou l&rsquo;assistance \u00e0 l&rsquo;exp\u00e9dition, veuillez contacter l&rsquo;\u00e9quipe de support Indogenmed avant de passer commande.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les comprim\u00e9s Moxif 400 Mg sont disponibles sur Indogenmed pour un acc\u00e8s fiable \u00e0 des produits pharmaceutiques de qualit\u00e9. Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision d&rsquo;un professionnel de sant\u00e9 qualifi\u00e9. Respectez toujours la posologie et la dur\u00e9e du traitement prescrites. Pour toute demande concernant les commandes en gros, la disponibilit\u00e9 ou l&rsquo;assistance \u00e0 [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[16254],"product_tag":[15902,15901],"igm_manufacturer":[],"class_list":["post-135526","product","type-product","status-publish","product_cat-mens-health-wellness","product_tag-strip","product_tag-tablet","pa_brand-name-moxif","pa_molecule-moxifloxacin","first","outofstock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/135526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=135526"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=135526"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=135526"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=135526"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=135526"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=135526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}