{"id":138763,"date":"2026-08-27T10:06:45","date_gmt":"2026-08-27T10:06:45","guid":{"rendered":"https:\/\/indogenmed.org\/product\/opti-zee-10-ml-tablets\/"},"modified":"2026-08-27T10:06:45","modified_gmt":"2026-08-27T10:06:45","slug":"opti-zee-10-ml-tablets","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/opti-zee-10-ml-tablets\/","title":{"rendered":"Opti Zee 10 Ml"},"content":{"rendered":"<p><strong>Opti Zee 10 Ml<\/strong> \u2014 principe actif : Carboxymethylcellulose. Forme : collyre. Dosage : 10 ML. Fabricant : Opti (Inde).<\/p>\n<p>Emballage : flacon. Quantit\u00e9 par emballage : 10 ML. Partie de la gamme Indogenmed Sant\u00e9 et bien-\u00eatre masculins.<\/p>\n<p>Une prescription valide est requise. Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision d&rsquo;un professionnel de sant\u00e9 qualifi\u00e9 et respecter la posologie et la dur\u00e9e du traitement prescrites par votre m\u00e9decin.<\/p>\n<p>Pour les demandes en gros, la disponibilit\u00e9 et le soutien \u00e0 l&rsquo;exp\u00e9dition, contactez l&rsquo;\u00e9quipe Indogenmed avant de passer une commande.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Opti Zee 10 Ml \u2014 principe actif : Carboxymethylcellulose. Forme : collyre. Dosage : 10 ML. Fabricant : Opti (Inde). Emballage : flacon. Quantit\u00e9 par emballage : 10 ML. Partie de la gamme Indogenmed Sant\u00e9 et bien-\u00eatre masculins. Une prescription valide est requise. Veuillez utiliser ce m\u00e9dicament uniquement sous la supervision d&rsquo;un professionnel de sant\u00e9 [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[11092],"product_cat":[16254],"product_tag":[16836,16682],"igm_manufacturer":[],"class_list":["post-138763","product","type-product","status-publish","product_brand-opti","product_cat-mens-health-wellness","product_tag-eye-drops","product_tag-vial-bottle","pa_brand-name-opti-zee","pa_molecule-carboxymethylcellulose","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/138763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=138763"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=138763"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=138763"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=138763"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=138763"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=138763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}