{"id":139063,"date":"2026-07-30T09:43:31","date_gmt":"2026-07-30T09:43:31","guid":{"rendered":"https:\/\/indogenmed.org\/product\/abhiforce-d-160-mg-tablets\/"},"modified":"2026-08-27T20:00:50","modified_gmt":"2026-08-27T20:00:50","slug":"abhiforce-d-160-mg-tablets","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/abhiforce-d-160-mg-tablets\/","title":{"rendered":"Abhiforce D 160 Mg Comprim\u00e9s"},"content":{"rendered":"<div id=\"model-response-message-contentr_823651891b5d0223\" dir=\"ltr\" aria-busy=\"false\" aria-live=\"polite\">\n<h2 data-path-to-node=\"0\">Abhiforce D 160 Mg Tablets | Dual-Action Sildenafil &amp; Dapoxetine Guide<\/h2>\n<p data-path-to-node=\"1\">Abhiforce D 160 Mg est un m\u00e9dicament oral combin\u00e9 utilis\u00e9 pour g\u00e9rer deux pr\u00e9occupations courantes de sant\u00e9 sexuelle masculine en m\u00eame temps : la dysfonction \u00e9rectile (DE) et l&rsquo;\u00e9jaculation pr\u00e9coce (EP).<\/p>\n<p data-path-to-node=\"1\">Fabriqu\u00e9 en Inde (Abhiflax Pharma Chem), chaque comprim\u00e9 enrob\u00e9 de film combine deux principes actifs : le citrate de sild\u00e9nafil (100 mg) et l&rsquo;hydrochlorure de dapox\u00e9tine (60 mg).<\/p>\n<p data-path-to-node=\"2\">En combinant la sild\u00e9nafil (qui soutient la fermet\u00e9 de l&rsquo;\u00e9rection) avec la dapox\u00e9tine (un inhibiteur s\u00e9lectif court de la recapture de la s\u00e9rotonine, ou ISRS, qui aide \u00e0 retarder l&rsquo;\u00e9jaculation), l&rsquo;Abhiforce D 160 Mg traite les deux pr\u00e9occupations de performance dans une seule pilule pratique.<\/p>\n<h3 data-path-to-node=\"3,0\">Important Medical Notice<\/h3>\n<p data-path-to-node=\"3,1\">L&rsquo;Abhiforce D 160 Mg est un m\u00e9dicament combin\u00e9 sur prescription. Ce guide est \u00e0 titre \u00e9ducatif uniquement et ne doit jamais remplacer une \u00e9valuation m\u00e9dicale r\u00e9elle par votre m\u00e9decin ou urologue. Consultez toujours un professionnel de sant\u00e9 agr\u00e9\u00e9 avant de prendre ou de modifier un m\u00e9dicament.<\/p>\n<h2 data-path-to-node=\"5\">How Abhiforce D 160 Mg Works in the Body<\/h2>\n<p data-path-to-node=\"6\">La dysfonction \u00e9rectile et l&rsquo;\u00e9jaculation pr\u00e9coce impliquent deux voies physiques compl\u00e8tement diff\u00e9rentes. L&rsquo;Abhiforce D utilise ses deux compos\u00e9s actifs pour traiter les deux simultan\u00e9ment :<\/p>\n<h3 data-path-to-node=\"7\">1. Soutien de l&rsquo;\u00e9rection physique (citrate de sild\u00e9nafil 100 mg)<\/h3>\n<ol start=\"1\" data-path-to-node=\"8\">\n<li>\n<p data-path-to-node=\"8,0,0\">Stimulation sexuelle naturelle : une stimulation physique ou \u00e9motionnelle signale \u00e0 votre corps de lib\u00e9rer l&rsquo;oxyde nitrique (NO) dans la r\u00e9gion pelvienne.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,1,0\">Activation de l&rsquo;enzyme : l&rsquo;oxyde nitrique d\u00e9clenche une enzyme appel\u00e9e guanylate cyclase.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,2,0\">Augmentation du cGMP : la guanylate cyclase augmente les niveaux de cGMP (guanosine monophosphate cyclique), un compos\u00e9 qui rel\u00e2che les tissus musculaires lisses et dilate les vaisseaux sanguins.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,3,0\">Blocage cibl\u00e9 de la PDE5 : la sild\u00e9nafil bloque l&rsquo;enzyme PDE5, emp\u00eachant sa d\u00e9gradation trop rapide du cGMP.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,4,0\">Flux sanguin am\u00e9lior\u00e9 : avec le cGMP maintenu actif plus longtemps, les vaisseaux sanguins restent dilat\u00e9s, permettant un flux sanguin sain vers les tissus p\u00e9niens et soutenant une \u00e9rection ferme.<\/p>\n<\/li>\n<\/ol>\n<h3 data-path-to-node=\"9\">2. Soutien du contr\u00f4le de l&rsquo;\u00e9jaculation (HCl de dapox\u00e9tine 60 mg)<\/h3>\n<ol start=\"1\" data-path-to-node=\"10\">\n<li>\n<p data-path-to-node=\"10,0,0\">Inhibition de la recapture de la s\u00e9rotonine : la dapox\u00e9tine ralentit le taux de recapture de la s\u00e9rotonine par les cellules nerveuses dans votre syst\u00e8me nerveux central.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"10,1,0\">R\u00e9flexe retard\u00e9 : en augmentant l&rsquo;activit\u00e9 de la s\u00e9rotonine dans les voies nerveuses, elle retarde le r\u00e9flexe d&rsquo;\u00e9jaculation, vous donnant un meilleur contr\u00f4le sur le moment du climax pendant l&rsquo;intimit\u00e9.<\/p>\n<\/li>\n<\/ol>\n<ul data-path-to-node=\"11\">\n<li>\n<p data-path-to-node=\"11,0,0\">N\u00e9cessite une stimulation sexuelle : l&rsquo;Abhiforce D 160 Mg ne vous donnera pas une \u00e9rection automatique. Il ne fonctionne que lorsque vous \u00eates naturellement excit\u00e9 ou stimul\u00e9 sexuellement.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"11,1,0\">Ne augmente pas la libido : ce m\u00e9dicament agit strictement sur les voies du flux sanguin et de la s\u00e9rotonine. Ce n&rsquo;est pas un aphrodisiaque, ni ne stimule vos niveaux hormonaux ou votre d\u00e9sir sexuel.<\/p>\n<\/li>\n<\/ul>\n<h2 data-path-to-node=\"13\">Product Quick Summary<\/h2>\n<p data-path-to-node=\"14\">Voici un aper\u00e7u rapide des sp\u00e9cifications de base pour les comprim\u00e9s Abhiforce D 160 Mg :<\/p>\n<table style=\"height: 342px;\" width=\"924\" data-path-to-node=\"15\">\n<thead>\n<tr>\n<td>Caract\u00e9ristique<\/td>\n<td>D\u00e9tails<\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Nom de marque<\/td>\n<td>Comprim\u00e9s Abhiforce D 160 Mg<\/td>\n<\/tr>\n<tr>\n<td>Principes actifs<\/td>\n<td>Citrate de sild\u00e9nafil (100 mg) + HCl de dapox\u00e9tine (60 mg)<\/td>\n<\/tr>\n<tr>\n<td>Classe de m\u00e9dicament<\/td>\n<td>Inhibiteur de la PDE5 + ISRS \u00e0 action courte<\/td>\n<\/tr>\n<tr>\n<td>Utilisations principales<\/td>\n<td>Dysfonction \u00e9rectile masculine (DE) &#038; \u00e9jaculation pr\u00e9coce (EP)<\/td>\n<\/tr>\n<tr>\n<td>Forme<\/td>\n<td>Comprim\u00e9 oral enrob\u00e9 de film \u00e0 avaler<\/td>\n<\/tr>\n<tr>\n<td>Commence \u00e0 agir en<\/td>\n<td>Environ 30 \u00e0 60 minutes<\/td>\n<\/tr>\n<tr>\n<td>Dur\u00e9e<\/td>\n<td>Environ 4 \u00e0 6 heures<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 data-path-to-node=\"17\">Principaux avantages des comprim\u00e9s \u00e0 action double<\/h2>\n<ul data-path-to-node=\"18\">\n<li>\n<p data-path-to-node=\"18,0,0\">Traite la DE et l&rsquo;EP ensemble : traite \u00e0 la fois la fermet\u00e9 de l&rsquo;\u00e9rection et le contr\u00f4le de l&rsquo;\u00e9jaculation avec une seule dose orale, sans avoir besoin de prendre deux comprim\u00e9s distincts.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"18,1,0\">Efficacit\u00e9 \u00e0 dose standard compl\u00e8te : combine des doses standard compl\u00e8tes de sild\u00e9nafil (100 mg) et de dapox\u00e9tine (60 mg) pour un soutien fiable des performances.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"18,2,0\">Restaure la confiance en soi : Aide \u00e0 \u00e9liminer l&rsquo;anxi\u00e9t\u00e9 de performance li\u00e9e \u00e0 une non-r\u00e9activit\u00e9 physique ou \u00e0 une \u00e9jaculation pr\u00e9coce.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"18,3,0\">Forme orale pratique : Facile \u00e0 avaler avec un verre d&rsquo;eau plate avant l&rsquo;intimit\u00e9 pr\u00e9vue.<\/p>\n<\/li>\n<\/ul>\n<h2 data-path-to-node=\"20\">Comment prendre les comprim\u00e9s Abhiforce D 160 Mg en toute s\u00e9curit\u00e9<\/h2>\n<p data-path-to-node=\"21\">Pour obtenir les meilleurs r\u00e9sultats et prot\u00e9ger votre sant\u00e9, suivez ces directives d&rsquo;utilisation simples :<\/p>\n<ul data-path-to-node=\"22\">\n<li>\n<p data-path-to-node=\"22,0,0\">Comment avaler le comprim\u00e9 : Avalez un comprim\u00e9 entier avec un verre plein d&rsquo;eau. Ne pas \u00e9craser, m\u00e2cher, diviser ou casser le comprim\u00e9.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"22,1,0\">Meilleur moment : Prenez votre comprim\u00e9 environ 30 \u00e0 60 minutes avant l&rsquo;activit\u00e9 sexuelle pr\u00e9vue.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"22,2,0\">Alimentation et repas : Vous pouvez le prendre avec ou sans nourriture. Prendre le comprim\u00e9 \u00e0 jeun favorise l&rsquo;absorption la plus rapide. \u00c9vitez les repas lourds ou riches en graisses juste avant l&rsquo;utilisation, car les graisses alimentaires peuvent retarder l&rsquo;entr\u00e9e du Sildenafil dans la circulation sanguine.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"22,3,0\">Limite \u00e0 un comprim\u00e9 par jour : Ne prenez jamais plus d&rsquo;un comprim\u00e9 de 160 mg dans une p\u00e9riode de 24 heures. D\u00e9passer la dose journali\u00e8re recommand\u00e9e peut provoquer une baisse s\u00e9v\u00e8re de la tension art\u00e9rielle, des vertiges et des effets secondaires dangereux.<\/p>\n<\/li>\n<\/ul>\n<h2 data-path-to-node=\"24\">Effets secondaires possibles \u00e0 conna\u00eetre<\/h2>\n<p data-path-to-node=\"25\">Comme Abhiforce D contient deux principes actifs, vous pouvez \u00e9prouver des effets secondaires l\u00e9gers pendant que votre corps s&rsquo;adapte. La plupart disparaissent lorsque le m\u00e9dicament quitte votre syst\u00e8me.<\/p>\n<h3 data-path-to-node=\"26\">Effets secondaires l\u00e9gers courants<\/h3>\n<ul data-path-to-node=\"27\">\n<li>\n<p data-path-to-node=\"27,0,0\">C\u00e9phal\u00e9es ou l\u00e9g\u00e8re vertige<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"27,1,0\">Rougeur du visage (chaleur, rougeur ou picotement du visage ou du cou)<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"27,2,0\">L\u00e9g\u00e8re naus\u00e9e ou inconfort gastrique<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"27,3,0\">Congestion nasale (nez bouch\u00e9) ou bouche s\u00e8che<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"27,4,0\">L\u00e9g\u00e8res modifications de la vision (telles qu&rsquo;une vision l\u00e9g\u00e8rement floue ou une teinte bleue)<\/p>\n<\/li>\n<\/ul>\n<h3 data-path-to-node=\"28\">Signes d&rsquo;alerte graves (Consultez imm\u00e9diatement un m\u00e9decin)<\/h3>\n<p data-path-to-node=\"29\">Arr\u00eatez de prendre le m\u00e9dicament et appelez un m\u00e9decin ou rendez-vous aux urgences si vous observez l&rsquo;un de ces probl\u00e8mes graves :<\/p>\n<ul data-path-to-node=\"30\">\n<li>\n<p data-path-to-node=\"30,0,0\">\u00c9rection qui dure trop longtemps (priapisme) : Une \u00e9rection douloureuse ou d&rsquo;une dur\u00e9e sup\u00e9rieure \u00e0 4 heures. Ne pas traiter peut causer des dommages permanents aux tissus du p\u00e9nis.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"30,1,0\">Perte soudaine de la vision ou de l&rsquo;audition : Une baisse ou une perte soudaine de la vision ou de l&rsquo;audition dans un ou les deux yeux ou oreilles.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"30,2,0\">Souffrance cardiaque : Douleur thoracique, essoufflement, vertige s\u00e9v\u00e8re ou sensation de syncope pendant l&rsquo;intimit\u00e9.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"30,3,0\">Suractivit\u00e9 de la s\u00e9rotonine : Fi\u00e8vre \u00e9lev\u00e9e, agitation s\u00e9v\u00e8re, tremblements musculaires ou confusion.<\/p>\n<\/li>\n<\/ul>\n<h2 data-path-to-node=\"32\">Avertissements de s\u00e9curit\u00e9 importants et restrictions<\/h2>\n<p data-path-to-node=\"33,0\">Avertissements critiques sur les nitrates et les ISRS<\/p>\n<p data-path-to-node=\"33,0\">Ne prenez jamais Abhiforce D 160 Mg si vous prenez des m\u00e9dicaments \u00e0 base de nitrates pour la douleur thoracique ou les probl\u00e8mes cardiaques (comme la nitroglyc\u00e9rine, l&rsquo;isosorbide ou les sprays contre la douleur thoracique). La combinaison du Sildenafil avec les nitrates provoque une chute brutale et s\u00e9v\u00e8re de la tension art\u00e9rielle pouvant entra\u00eener des \u00e9vanouissements, un infarctus ou un accident vasculaire c\u00e9r\u00e9bral.<\/p>\n<p data-path-to-node=\"33,1\">De plus, ne combinez pas ce m\u00e9dicament avec des m\u00e9dicaments psychiatriques, des inhibiteurs de la MAO ou d&rsquo;autres ISRS\/SNRIs. La combinaison de la Dapoxetine avec des antid\u00e9presseurs peut d\u00e9clencher un \u00e9tat dangereux appel\u00e9 syndrome s\u00e9rotoninergique.<\/p>\n<ul data-path-to-node=\"34\">\n<li>\n<p data-path-to-node=\"34,0,0\">Conditions cardiaques : Ne prenez pas ce m\u00e9dicament si vous avez eu un infarctus, un accident vasculaire c\u00e9r\u00e9bral, une insuffisance cardiaque s\u00e9v\u00e8re ou une hypertension non contr\u00f4l\u00e9e dans les 6 derniers mois.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"34,1,0\">Soins du foie et des reins : Les hommes atteints d&rsquo;une insuffisance h\u00e9patique ou r\u00e9nale s\u00e9v\u00e8re \u00e9liminent le Sildenafil et la Dapoxetine plus lentement et n\u00e9cessitent une \u00e9valuation m\u00e9dicale avant l&rsquo;utilisation.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"34,2,0\">Alcool et pamplemousse : \u00c9vitez compl\u00e8tement l&rsquo;alcool pendant la prise de ce m\u00e9dicament. L&rsquo;alcool renforce les effets s\u00e9datifs de la Dapoxetine, augmentant le risque de vertiges s\u00e9v\u00e8res, d&rsquo;\u00e9vanouissements et de c\u00e9phal\u00e9es. \u00c9vitez de consommer du pamplemousse ou du jus de pamplemousse, car cela peut augmenter les concentrations du m\u00e9dicament dans le sang \u00e0 des niveaux dangereux.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"34,3,0\">Qui ne devrait pas le prendre : Les comprim\u00e9s Abhiforce D 160 Mg sont strictement r\u00e9serv\u00e9s aux hommes adultes de plus de 18 ans. Les femmes et les enfants ne doivent jamais prendre ce m\u00e9dicament.<\/p>\n<\/li>\n<\/ul>\n<h2 data-path-to-node=\"36\">Questions fr\u00e9quentes (FAQ)<\/h2>\n<h3 data-path-to-node=\"37\">\u00c0 quoi sert Abhiforce D 160 Mg ?<\/h3>\n<p data-path-to-node=\"38\">Il est utilis\u00e9 pour traiter \u00e0 la fois la dysfonction \u00e9rectile (DE) et l&rsquo;\u00e9jaculation pr\u00e9coce (EP) chez les hommes adultes, aidant \u00e0 obtenir une \u00e9rection ferme tout en prolongeant le contr\u00f4le de l&rsquo;\u00e9jaculation.<\/p>\n<h3 data-path-to-node=\"39\">Combien de temps faut-il pour que les comprim\u00e9s commencent \u00e0 agir ?<\/h3>\n<p data-path-to-node=\"40\">Il commence g\u00e9n\u00e9ralement \u00e0 agir dans les 30 \u00e0 60 minutes suivant la prise, lorsqu&rsquo;il est pris avec un verre d&rsquo;eau et qu&rsquo;une excitation sexuelle naturelle est pr\u00e9sente.<\/p>\n<h3 data-path-to-node=\"41\">Combien de temps durent les effets ?<\/h3>\n<p data-path-to-node=\"42\">L&rsquo;effet th\u00e9rapeutique de la combinaison de Sildenafil et Dapoxetine dure g\u00e9n\u00e9ralement entre 4 et 6 heures.<\/p>\n<h3 data-path-to-node=\"43\">Puis-je boire de l&rsquo;alcool avec les comprim\u00e9s Abhiforce D ?<\/h3>\n<p data-path-to-node=\"44\">Non. Vous devez \u00e9viter l&rsquo;alcool pendant la prise de ce produit. La combinaison de l&rsquo;alcool avec la Dapoxetine augmente consid\u00e9rablement le risque de vertiges s\u00e9v\u00e8res, de vertiges, d&rsquo;\u00e9vanouissements et de somnolence.<\/p>\n<h2 data-path-to-node=\"46\">R\u00e9f\u00e9rences<\/h2>\n<ul data-path-to-node=\"47\">\n<li>\n<p data-path-to-node=\"47,0,0\">Pour les propri\u00e9t\u00e9s des compos\u00e9s actifs et le m\u00e9canisme (Sildenafil) :<\/p>\n<p data-path-to-node=\"47,0,1\">Centre national pour l&rsquo;information biotechnologique (NCBI). (n.d.). R\u00e9sum\u00e9 de la substance chimique PubChem pour le CID 135398744 : Sildenafil Citrate. Base de donn\u00e9es PubChem. <a href=\"https:\/\/www.google.com\/search?q=https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/Sildenafil-citrate\" target=\"_blank\" rel=\"noopener nofollow\" data-hveid=\"0\" data-ved=\"0CAAQ_4QMahgKEwj0s6CkrvqVAxUAAAAAHQAAAAAQxQM\">https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/Sildenafil-citrate<\/a><\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"47,1,0\">Pour l&rsquo;efficacit\u00e9 combin\u00e9e de la Dapoxetine et de la Sildenafil :<\/p>\n<p data-path-to-node=\"47,1,1\">Centre national de m\u00e9decine compl\u00e9mentaire et int\u00e9grative (PMC). (n.d.). Efficacit\u00e9 et s\u00e9curit\u00e9 de la th\u00e9rapie combin\u00e9e chez les hommes atteints de dysfonction \u00e9rectile et d&rsquo;\u00e9jaculation pr\u00e9coce. <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC2699643\/\" target=\"_blank\" rel=\"noopener nofollow\" data-hveid=\"0\" data-ved=\"0CAAQ_4QMahgKEwj0s6CkrvqVAxUAAAAAHQAAAAAQxgM\">https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC2699643\/<\/a><\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"47,2,0\">Pour les protocoles officiels de dosage et les donn\u00e9es de monographie :<\/p>\n<p data-path-to-node=\"47,2,1\">Drugs.com. (n.d.). Monographie de Sildenafil pour les professionnels : actions, dosage et effets secondaires. Portail de directives Drugs.com. <a href=\"https:\/\/www.drugs.com\/monograph\/sildenafil.html\" target=\"_blank\" rel=\"noopener nofollow\" data-hveid=\"0\" data-ved=\"0CAAQ_4QMahgKEwj0s6CkrvqVAxUAAAAAHQAAAAAQxwM\">https:\/\/www.drugs.com\/monograph\/sildenafil.html<\/a><\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"47,3,0\">Pour la s\u00e9curit\u00e9 g\u00e9n\u00e9rale des patients, les effets secondaires et les avertissements d&rsquo;interactions :<\/p>\n<p data-path-to-node=\"47,3,1\">WebMD. (n.d.). Sildenafil oral : utilisations, effets secondaires, interactions et avertissements. Encyclop\u00e9die des m\u00e9dicaments WebMD. <a href=\"https:\/\/www.webmd.com\/drugs\/2\/drug-7418\/sildenafil-oral\/details\" target=\"_blank\" rel=\"noopener nofollow\" data-hveid=\"0\" data-ved=\"0CAAQ_4QMahgKEwj0s6CkrvqVAxUAAAAAHQAAAAAQyAM\">https:\/\/www.webmd.com\/drugs\/2\/drug-7418\/sildenafil-oral\/details<\/a><\/p>\n<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Abhiforce D 160 Mg Tablets | Dual-Action Sildenafil &amp; Dapoxetine Guide Abhiforce D 160 Mg est un m\u00e9dicament oral combin\u00e9 utilis\u00e9 pour g\u00e9rer deux pr\u00e9occupations courantes de sant\u00e9 sexuelle masculine en m\u00eame temps : la dysfonction \u00e9rectile (DE) et l&rsquo;\u00e9jaculation pr\u00e9coce (EP). Fabriqu\u00e9 en Inde (Abhiflax Pharma Chem), chaque comprim\u00e9 enrob\u00e9 de film combine deux [&hellip;]<\/p>\n","protected":false},"featured_media":128178,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[24944],"product_cat":[16197,16253,16254],"product_tag":[15901],"igm_manufacturer":[],"class_list":["post-139063","product","type-product","status-publish","has-post-thumbnail","product_brand-hab-pharma","product_cat-sexual-wellness","product_cat-erectile-dysfunction","product_cat-mens-health-wellness","product_tag-tablet","pa_brand-name-abhiforce-d","pa_molecule-sildenafil-dapoxetine","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/139063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=139063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media\/128178"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=139063"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=139063"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=139063"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=139063"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=139063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}