{"id":45397,"date":"2025-12-09T13:28:29","date_gmt":"2025-12-09T13:28:29","guid":{"rendered":"https:\/\/indogenmed.org\/product\/ascimib-40-mg-tablet\/"},"modified":"2026-08-11T04:16:10","modified_gmt":"2026-08-11T04:16:10","slug":"ascimib-40-mg-tablets","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/ascimib-40-mg-tablets\/","title":{"rendered":"Comprim\u00e9 d&rsquo;Ascimib 40 mg"},"content":{"rendered":"<p>Ascimib 40 mg, comprim\u00e9, est un m\u00e9dicament oral sur ordonnance utilis\u00e9 dans le traitement du cancer du sang, et plus particuli\u00e8rement de la leuc\u00e9mie my\u00e9lo\u00efde chronique (LMC). Il contient l&rsquo;asciminib, un principe actif qui agit en ciblant les cellules canc\u00e9reuses et en ralentissant ou en stoppant leur croissance. Ascimib 40 mg, comprim\u00e9, est prescrit par les oncologues aux patients atteints de LMC n\u00e9cessitant un traitement sp\u00e9cialis\u00e9 et doit \u00eatre pris sous stricte surveillance m\u00e9dicale.<\/p>\n<h2> Utilisations du comprim\u00e9 d&rsquo;Ascimib 40 mg<\/h2>\n<p> L&rsquo;asciminib est utilis\u00e9 pour\u00a0:<\/p>\n<ul>\n<li> Traitement de la leuc\u00e9mie my\u00e9lo\u00efde chronique (LMC)<\/li>\n<\/ul>\n<h2> Comment fonctionne le comprim\u00e9 Ascimib 40 mg<\/h2>\n<p> L&rsquo;asciminib agit en bloquant l&rsquo;activit\u00e9 d&rsquo;une prot\u00e9ine anormale qui incite les cellules canc\u00e9reuses \u00e0 se multiplier de fa\u00e7on incontr\u00f4l\u00e9e. En inhibant cette prot\u00e9ine, l&rsquo;asciminib contribue \u00e0\u00a0:<\/p>\n<ul>\n<li> Ralentir la croissance des cellules canc\u00e9reuses<\/li>\n<li> Pr\u00e9venir la propagation du cancer<\/li>\n<li> Contr\u00f4ler la progression de la maladie<\/li>\n<\/ul>\n<p> Ce m\u00e9canisme cibl\u00e9 contribue \u00e0 prot\u00e9ger les cellules saines tout en agissant sp\u00e9cifiquement sur les cellules canc\u00e9reuses.<\/p>\n<h2> Effets secondaires courants du comprim\u00e9 d&rsquo;Ascimib 40 mg<\/h2>\n<p> La plupart des effets secondaires sont g\u00e9n\u00e9ralement b\u00e9nins et disparaissent souvent \u00e0 mesure que votre corps s&rsquo;habitue au m\u00e9dicament. Toutefois, consultez votre m\u00e9decin si certains effets secondaires persistent ou vous inqui\u00e8tent.<\/p>\n<h3> Effets secondaires courants<\/h3>\n<ul>\n<li> infection des voies respiratoires sup\u00e9rieures<\/li>\n<li> Douleurs musculo-squelettiques (douleurs osseuses, musculaires ou articulaires)<\/li>\n<li> Fatigue<\/li>\n<li> Naus\u00e9e<\/li>\n<li> \u00c9ruption cutan\u00e9e<\/li>\n<li> Diarrh\u00e9e<\/li>\n<li> plaquettes sanguines faibles<\/li>\n<li> Augmentation du taux de triglyc\u00e9rides dans le sang<\/li>\n<li> Diminution du nombre de globules blancs (neutrophiles)<\/li>\n<li> Diminution du taux d&rsquo;h\u00e9moglobine<\/li>\n<li> cr\u00e9atine kinase \u00e9lev\u00e9e<\/li>\n<li> Augmentation de l&rsquo;alanine aminotransf\u00e9rase (ALT)<\/li>\n<li> Augmentation des taux de lipase dans le sang<\/li>\n<li> Taux d&rsquo;amylase s\u00e9rique \u00e9lev\u00e9s<\/li>\n<\/ul>\n<h2> Note importante<\/h2>\n<p> Ascimib 40 mg est un m\u00e9dicament anticanc\u00e9reux puissant et doit \u00eatre pris exactement comme prescrit par votre m\u00e9decin. Des analyses de sang r\u00e9guli\u00e8res et des consultations de suivi peuvent \u00eatre n\u00e9cessaires pour surveiller votre r\u00e9ponse au traitement et d\u00e9tecter rapidement tout effet ind\u00e9sirable. N&rsquo;interrompez pas le traitement et ne modifiez pas la dose sans consulter votre professionnel de sant\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ascimib 40 mg, comprim\u00e9, est un m\u00e9dicament oral sur ordonnance utilis\u00e9 dans le traitement du cancer du sang, et plus particuli\u00e8rement de la leuc\u00e9mie my\u00e9lo\u00efde chronique (LMC). Il contient l&rsquo;asciminib, un principe actif qui agit en ciblant les cellules canc\u00e9reuses et en ralentissant ou en stoppant leur croissance. Ascimib 40 mg, comprim\u00e9, est prescrit par [&hellip;]<\/p>\n","protected":false},"featured_media":110831,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[3175],"product_cat":[15890,15891],"product_tag":[16774,16775,15939,15901],"igm_manufacturer":[],"class_list":["post-45397","product","type-product","status-publish","has-post-thumbnail","product_brand-everest-pharmaceuticals","product_cat-blood-cancer","product_cat-oncology","product_tag-ascimib","product_tag-asciminib","product_tag-bottle","product_tag-tablet","pa_brand-name-ascimib","pa_molecule-asciminib","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/45397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=45397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media\/110831"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=45397"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=45397"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=45397"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=45397"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=45397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}