{"id":70726,"date":"2026-03-09T11:50:21","date_gmt":"2026-03-09T11:50:21","guid":{"rendered":"https:\/\/indogenmed.org\/?post_type=product&#038;p=70726"},"modified":"2026-08-27T19:25:27","modified_gmt":"2026-08-27T19:25:27","slug":"syndyma-400mg-injection","status":"publish","type":"product","link":"https:\/\/indogenmed.org\/fr\/product\/syndyma-400mg-injection\/","title":{"rendered":"Syndyma 400mg Injection"},"content":{"rendered":"<p>Syndyma 400mg Injection est un m\u00e9dicament principalement utilis\u00e9 pour g\u00e9rer certains types de cancer. Son principe actif n&rsquo;est pas explicitement indiqu\u00e9 dans le nom du produit, mais il s&rsquo;agit g\u00e9n\u00e9ralement d&rsquo;un agent cytotoxique con\u00e7u pour cibler et inhiber la croissance des cellules canc\u00e9reuses en division rapide. Syndyma agit en interf\u00e9rant avec le processus de division cellulaire, entra\u00eenant la mort des cellules canc\u00e9reuses. Il est indiqu\u00e9 pour le traitement de malignit\u00e9s sp\u00e9cifiques, souvent en combinaison avec d&rsquo;autres th\u00e9rapies. La posologie et l&rsquo;administration de Syndyma 400mg Injection sont d\u00e9termin\u00e9es par un professionnel de sant\u00e9 qualifi\u00e9 en fonction du type et de l&rsquo;\u00e9tape du cancer, ainsi que de l&rsquo;\u00e9tat de sant\u00e9 g\u00e9n\u00e9ral du patient. Les effets ind\u00e9sirables courants peuvent inclure des naus\u00e9es, des vomissements, une perte de cheveux, de la fatigue et une suppression de la moelle osseuse, entre autres. Les patients doivent signaler imm\u00e9diatement toute r\u00e9action adverse \u00e0 leur m\u00e9decin. Syndyma 400mg Injection doit \u00eatre conserv\u00e9 conform\u00e9ment aux instructions du fabricant, g\u00e9n\u00e9ralement \u00e0 temp\u00e9rature ambiante, \u00e0 l&rsquo;abri de la lumi\u00e8re et de l&rsquo;humidit\u00e9, et hors de port\u00e9e des enfants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Syndyma 400mg Injection est un m\u00e9dicament principalement utilis\u00e9 pour g\u00e9rer certains types de cancer. Son principe actif n&rsquo;est pas explicitement indiqu\u00e9 dans le nom du produit, mais il s&rsquo;agit g\u00e9n\u00e9ralement d&rsquo;un agent cytotoxique con\u00e7u pour cibler et inhiber la croissance des cellules canc\u00e9reuses en division rapide. Syndyma agit en interf\u00e9rant avec le processus de division [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[3147],"product_cat":[16211,15891],"product_tag":[18298,15985,23603,15986],"igm_manufacturer":[],"class_list":["post-70726","product","type-product","status-publish","product_brand-cipla-ltd","product_cat-breast-cancer","product_cat-oncology","product_tag-imatinib","product_tag-injection","product_tag-syndyma","product_tag-vial","pa_brand-name-syndyma","pa_molecule-imatinib","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product\/70726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/comments?post=70726"}],"wp:attachment":[{"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/media?parent=70726"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_brand?post=70726"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_cat?post=70726"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/product_tag?post=70726"},{"taxonomy":"igm_manufacturer","embeddable":true,"href":"https:\/\/indogenmed.org\/fr\/wp-json\/wp\/v2\/igm_manufacturer?post=70726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}